{"id":36131,"date":"2023-08-25T16:03:31","date_gmt":"2023-08-25T14:03:31","guid":{"rendered":"https:\/\/teasense.ch\/?post_type=product&#038;p=36131"},"modified":"2024-05-30T10:20:18","modified_gmt":"2024-05-30T08:20:18","slug":"hafer-drink-pulver","status":"publish","type":"product","link":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/","title":{"rendered":"Hafer-Drink-Pulver"},"content":{"rendered":"<p>Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei. Vermeide unn\u00f6tige Inhaltsstoffe, Verpackungsm\u00fcll und reduziere Verschwendung von abgelaufenen Resten.<\/p>\n<h3>Du kannst mit dem Pulver ganz einfach deine Hafermilch selber machen.<\/h3>\n<h3><strong>Anwendung<\/strong><\/h3>\n<p>Zun\u00e4chst sollten 50 g bis 80 g Pulver mit drei Essl\u00f6ffel Wasser klumpenfrei verr\u00fchrt werden. Dann 500 ml kaltes Wasser hinzuf\u00fcgen und gut verr\u00fchren.<\/p>\n<p>Das Ergebnis ist ein vollmundiger Haferdrink, der sich perfekt zum Kochen, Backen oder einfach als erfrischendes Getr\u00e4nk eignet. Das Pulver l\u00e4sst sich zudem problemlos auf Reisen mitnehmen und spart Platz im Gep\u00e4ck. Der Geschmack des Haferdrinks \u00fcberzeugt durch seine nat\u00fcrliche S\u00fcsse und die angenehme Konsistenz &#8211; ohne den Einsatz von k\u00fcnstlichen Aromen oder Zusatzstoffen.<\/p>\n<p>Doch nicht nur geschmacklich hat das Haferdrinkpulver einiges zu bieten: Es ist auch eine nachhaltige Alternative zur herk\u00f6mmlichen Milchproduktion. Die Herstellung von tierischen Produkten verursacht einen hohen CO2-Ausstoss sowie Wasserverbrauch und tr\u00e4gt somit massgeblich zur Umweltbelastung bei. Mit dem Verzicht auf Tiermilch zugunsten pflanzlicher Alternativen k\u00f6nnen wir alle dazu beitragen, unseren \u00f6kologischen Fussabdruck zu reduzieren.<\/p>\n<p>Also worauf wartest du noch? Probiere jetzt unser veganes Haferdrinkpulver aus!<\/p>\n<h3><strong>Zutaten Hafer-Drink-Pulver<\/strong><\/h3>\n<p>Hafervollkornmehl, Salz<\/p>\n<p>Hinweis f\u00fcr Allergiker: Kann Spuren von Lupine, Mandeln und Sesam enthalten.<\/p>\n<p><strong>Durchschnittliche N\u00e4hrwerte per 100g Pulver<br \/>\n<\/strong>Energie 429kcal\/1796kJ<br \/>\nFett 7g (davon ges\u00e4ttigt 1,5g)<br \/>\nKohlenhydrate 71,7g (davon Zucker 17,0g)<br \/>\nBallaststoffe 9,5g<br \/>\nEiweiss 15,0g<br \/>\nSalz 0,7g<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hafer-Drink-Pulver glutenfrei &amp; vegan, ohne Zuckerzusatz &#8211; als Drink oder Zutat<\/p>\n<p><strong>Produktalternative <a href=\"https:\/\/teasense.ch\/produkt\/haferdrink-pulver\/\">DYI Haferdrink Pulver<\/a><\/strong><\/p>\n","protected":false},"featured_media":36140,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[74],"product_tag":[],"class_list":["post-36131","product","type-product","status-publish","has-post-thumbnail","product_cat-alle-produkte","pa_herkunft-eu-landwirtschaft","pa_weight-100-g","pa_weight-300-g","first","outofstock","shipping-taxable","product-type-variable","has-default-attributes","add-to-wishlist-before_image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hafer-Drink-Pulver - TeaSense.ch<\/title>\n<meta name=\"description\" content=\"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hafer-Drink-Pulver - TeaSense.ch\" \/>\n<meta property=\"og:description\" content=\"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/\" \/>\n<meta property=\"og:site_name\" content=\"TeaSense.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teasense.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T08:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/haferdrink-hauptbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/\",\"url\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/\",\"name\":\"Hafer-Drink-Pulver - TeaSense.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/haferdrink-hauptbild.jpg\",\"datePublished\":\"2023-08-25T14:03:31+00:00\",\"dateModified\":\"2024-05-30T08:20:18+00:00\",\"description\":\"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/#breadcrumb\"},\"inLanguage\":\"en-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CH\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/haferdrink-hauptbild.jpg\",\"contentUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/haferdrink-hauptbild.jpg\",\"width\":800,\"height\":800,\"caption\":\"Hafer-Drink-Pulver auf farbigem Hintergrund\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/product\\\/hafer-drink-pulver\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/teasense.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online Tea Shop Switzerland\",\"item\":\"https:\\\/\\\/teasense.ch\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hafer-Drink-Pulver\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/teasense.ch\\\/en\\\/\",\"name\":\"TeaSense.ch\",\"description\":\"Nat\u00fcrliche Teemischungen und klassischer Tee\",\"publisher\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#organization\"},\"alternateName\":\"TeaSense\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teasense.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#organization\",\"name\":\"Reale Selection\",\"alternateName\":\"TeaSense.ch\",\"url\":\"https:\\\/\\\/teasense.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CH\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg\",\"contentUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg\",\"width\":512,\"height\":512,\"caption\":\"Reale Selection\"},\"image\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teasense.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hafer-Drink-Pulver - TeaSense.ch","description":"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/","og_locale":"en_US","og_type":"article","og_title":"Hafer-Drink-Pulver - TeaSense.ch","og_description":"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.","og_url":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/","og_site_name":"TeaSense.ch","article_publisher":"https:\/\/www.facebook.com\/teasense.ch","article_modified_time":"2024-05-30T08:20:18+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/haferdrink-hauptbild.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/","url":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/","name":"Hafer-Drink-Pulver - TeaSense.ch","isPartOf":{"@id":"https:\/\/teasense.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/#primaryimage"},"image":{"@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/#primaryimage"},"thumbnailUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/haferdrink-hauptbild.jpg","datePublished":"2023-08-25T14:03:31+00:00","dateModified":"2024-05-30T08:20:18+00:00","description":"Der perfekte vegane Milchersatz f\u00fcr Zuhause oder auch unterwegs. Das Produkt ist ausserdem ausgewiesen glutenfrei - vermeide unn\u00f6tige Inhaltsstoffe.","breadcrumb":{"@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/#breadcrumb"},"inLanguage":"en-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/"]}]},{"@type":"ImageObject","inLanguage":"en-CH","@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/#primaryimage","url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/haferdrink-hauptbild.jpg","contentUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/haferdrink-hauptbild.jpg","width":800,"height":800,"caption":"Hafer-Drink-Pulver auf farbigem Hintergrund"},{"@type":"BreadcrumbList","@id":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/teasense.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Online Tea Shop Switzerland","item":"https:\/\/teasense.ch\/shop\/"},{"@type":"ListItem","position":3,"name":"Hafer-Drink-Pulver"}]},{"@type":"WebSite","@id":"https:\/\/teasense.ch\/en\/#website","url":"https:\/\/teasense.ch\/en\/","name":"TeaSense.ch","description":"Nat\u00fcrliche Teemischungen und klassischer Tee","publisher":{"@id":"https:\/\/teasense.ch\/en\/#organization"},"alternateName":"TeaSense","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teasense.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CH"},{"@type":"Organization","@id":"https:\/\/teasense.ch\/en\/#organization","name":"Reale Selection","alternateName":"TeaSense.ch","url":"https:\/\/teasense.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-CH","@id":"https:\/\/teasense.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/07\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg","contentUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/07\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg","width":512,"height":512,"caption":"Reale Selection"},"image":{"@id":"https:\/\/teasense.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teasense.ch"]}]}},"jetpack-related-posts":[{"id":44143,"url":"https:\/\/teasense.ch\/en\/product\/hafer-drink-pulver-eu\/","url_meta":{"origin":36131,"position":0},"title":"Hafer-Drink Pulver \u2013 Pflanzlicher Milchersatz aus der EU","author":"Reale Selection","date":"25. February 2025","format":false,"excerpt":"Rabatt wegen MHD 31.03.2026 Zubereitung Hafer-Drink Pulver von Europa \ud83e\udd44 50 - 80 g Pulver auf 500 ml Wasser \ud83c\udf21\ufe0f Kalt oder warm \ud83c\udf00 Gut verr\u00fchren","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Hafer Drink Milch Pulver EU","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Hafer-Drink-Milch-Pulver-EU.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Hafer-Drink-Milch-Pulver-EU.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Hafer-Drink-Milch-Pulver-EU.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Hafer-Drink-Milch-Pulver-EU.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50537,"url":"https:\/\/teasense.ch\/product\/ube-latte-pulver\/","url_meta":{"origin":36131,"position":1},"title":"Ube-Latte-Pulver","author":"Reale Selection","date":"9. May 2026","format":false,"excerpt":"Zubereitung Ube Latte \ud83d\udc9c \ud83e\udd44 2\u20133 g Ube-Latte-Pulver \ud83d\udca7 Mit 150\u2013200 ml lauwarmem Wasser verr\u00fchren \ud83e\udd5b Mit Milch oder Pflanzendrink mischen \u2728 Nach Belieben s\u00fcssen oder aufsch\u00e4umen","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Ube-Latte-Pulver 100g","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/ube-latte-pulver-100g.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/ube-latte-pulver-100g.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/ube-latte-pulver-100g.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/ube-latte-pulver-100g.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":44138,"url":"https:\/\/teasense.ch\/en\/product\/reis-drink-pulver-eu\/","url_meta":{"origin":36131,"position":2},"title":"Reis-Drink Pulver \u2013 Pflanzlicher Milchersatz aus der EU","author":"Reale Selection","date":"25. February 2025","format":false,"excerpt":"Zubereitung Reis-Drink Pulver \ud83e\udd44 50 - 80 g Pulver auf 500 ml Wasser\ud83c\udf21\ufe0f Kalt oder warm\ud83c\udf00 Gut verr\u00fchren","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Reis Milch Reis Drink Pulver EU","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Reis-Milch-Reis-Drink-Pulver-EU.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Reis-Milch-Reis-Drink-Pulver-EU.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Reis-Milch-Reis-Drink-Pulver-EU.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Reis-Milch-Reis-Drink-Pulver-EU.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50749,"url":"https:\/\/teasense.ch\/product\/spirulina-pulver\/","url_meta":{"origin":36131,"position":3},"title":"Spirulina Pulver","author":"Reale Selection","date":"12. May 2026","format":false,"excerpt":"\ud83e\udd44 Nach Belieben in Getr\u00e4nke oder Speisen einr\u00fchren\ud83e\udd64 Ideal f\u00fcr Smoothies, Bowls und kreative Drinks\ud83d\udc9a Nat\u00fcrlich dunkelgr\u00fcn","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Spirulina Pulver","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/sp.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/sp.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/sp.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2026\/05\/sp.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":36099,"url":"https:\/\/teasense.ch\/en\/product\/reis-drink-pulver\/","url_meta":{"origin":36131,"position":4},"title":"Reis-Drink Pulver","author":"Reale Selection","date":"25. August 2023","format":false,"excerpt":"Reis-Drink Pulver glutenfrei, vegan, koscher, halal und ohne Zuckerzusatz 1 Kilo Variante auf Anfrage wieder erh\u00e4ltlich (Lieferzeit ca. 5-10 Werktage)","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Reis-Drink Pulver Milchspritzer","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/reis-drink-pulver.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/reis-drink-pulver.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/reis-drink-pulver.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/reis-drink-pulver.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":44318,"url":"https:\/\/teasense.ch\/product\/houjicha-pulver-geroesteter-gruentee\/","url_meta":{"origin":36131,"position":5},"title":"Houjicha Pulver \u2013 Ger\u00f6steter Gr\u00fcntee","author":"Reale Selection","date":"27. February 2025","format":false,"excerpt":"Zubereitung \u2013 Houjicha Tee - Klassische Variante \ud83e\udd44 1 TL Houjicha Pulver auf 200 ml Wasser\ud83c\udf21\ufe0f 80 \u00b0C \u2013 nicht kochend, sondern leicht abgek\u00fchlt\ud83c\udf00 ca. 30 Sekunden gut verr\u00fchren und direkt geniesse","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"Houjicha Pulver","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Houjicha-Pulver.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Houjicha-Pulver.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Houjicha-Pulver.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2025\/02\/Houjicha-Pulver.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":false,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/product\/36131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/comments?post=36131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/media\/36140"}],"wp:attachment":[{"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/media?parent=36131"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/product_brand?post=36131"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/product_cat?post=36131"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/teasense.ch\/en\/wp-json\/wp\/v2\/product_tag?post=36131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}