{"id":51394,"date":"2023-05-10T22:07:11","date_gmt":"2023-05-10T20:07:11","guid":{"rendered":"https:\/\/teasense.ch\/informativa-sulla-privacy\/"},"modified":"2023-05-10T22:07:11","modified_gmt":"2023-05-10T20:07:11","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-WEB:5c592ac4-01be-4825-9cd1-88383b1bca03-9\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:5c592ac4-01be-4825-9cd1-88383b1bca03-9\" data-turn-id-container=\"request-WEB:5c592ac4-01be-4825-9cd1-88383b1bca03-9\" data-testid=\"conversation-turn-20\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"3c9ba6bb-dca2-478b-a2e0-e252f329aa96\" data-message-model-slug=\"gpt-5-3-mini\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"119\" data-end=\"148\"><strong data-start=\"119\" data-end=\"148\">Informativa sulla privacy<\/strong><\/p>\n<p data-start=\"150\" data-end=\"475\">La presente informativa sulla privacy ti spiega in modo chiaro come raccogliamo, utilizziamo e trattiamo i dati personali sul nostro sito <a class=\"decorated-link\" href=\"https:\/\/teasense.ch\/it\/\" target=\"_new\" rel=\"noopener\" data-start=\"288\" data-end=\"307\">https:\/\/teasense.ch<\/a> (di seguito \u201csito\u201d) da parte di Reale Selection (di seguito \u201cnoi\u201d). Ti informa inoltre sui tuoi diritti in materia di protezione dei dati secondo le leggi applicabili.<\/p>\n<p data-start=\"477\" data-end=\"582\">Nome dell\u2019azienda: Reale Selection<br data-start=\"511\" data-end=\"514\" \/>Reale Selection<br data-start=\"529\" data-end=\"532\" \/>Schaffhauserstrasse 526<br data-start=\"555\" data-end=\"558\" \/>8052 Zurigo<br data-start=\"569\" data-end=\"572\" \/>Svizzera<\/p>\n<p data-start=\"584\" data-end=\"646\">Email: <a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"591\" data-end=\"615\">realeselection@gmail.com<\/a><br data-start=\"615\" data-end=\"618\" \/>Telefono: +41 76 405 70 00<\/p>\n<p data-start=\"648\" data-end=\"702\">Responsabile della protezione dei dati: Romina Reale<\/p>\n<h2 data-section-id=\"qdc3jl\" data-start=\"704\" data-end=\"728\">Informazioni generali<\/h2>\n<p data-start=\"729\" data-end=\"947\">In conformit\u00e0 all\u2019articolo 13 della Costituzione federale svizzera e alla legge federale sulla protezione dei dati (LPD), ogni persona ha diritto alla protezione della propria sfera privata e dei propri dati personali.<\/p>\n<p data-start=\"949\" data-end=\"1101\">Attribuiamo grande importanza alla protezione dei tuoi dati personali e li trattiamo in modo confidenziale e secondo le disposizioni legali applicabili.<\/p>\n<p data-start=\"1103\" data-end=\"1256\">In collaborazione con i nostri fornitori di hosting, adottiamo misure adeguate per proteggere i dati da accessi non autorizzati, perdita o uso improprio.<\/p>\n<p data-start=\"1258\" data-end=\"1402\">Ti segnaliamo che la trasmissione di dati su Internet pu\u00f2 comportare rischi di sicurezza e che una protezione assoluta non pu\u00f2 essere garantita.<\/p>\n<p data-start=\"1404\" data-end=\"1503\">Utilizzando questo sito, accetti il trattamento dei dati come descritto nella presente informativa.<\/p>\n<h2 data-section-id=\"jzqt4r\" data-start=\"1505\" data-end=\"1523\">Dati di accesso<\/h2>\n<p data-start=\"1524\" data-end=\"1781\">Il sito pu\u00f2 essere visitato senza registrazione. Durante la visita, il server pu\u00f2 registrare automaticamente informazioni tecniche come pagina visitata, data, ora e file consultati a fini statistici. Questi dati non permettono di identificarti direttamente.<\/p>\n<p data-start=\"1783\" data-end=\"1960\">Se ci fornisci dati personali come nome o indirizzo email, ci\u00f2 avviene sempre su base volontaria, ove possibile. Questi dati non vengono trasmessi a terzi senza il tuo consenso.<\/p>\n<h2 data-section-id=\"639c4f\" data-start=\"1962\" data-end=\"1995\">Trattamento dei dati personali<\/h2>\n<p data-start=\"1996\" data-end=\"2113\">Per dati personali si intendono tutte le informazioni che si riferiscono a una persona identificata o identificabile.<\/p>\n<p data-start=\"2115\" data-end=\"2263\">Il trattamento comprende qualsiasi operazione relativa a questi dati come raccolta, conservazione, utilizzo, modifica, trasmissione o cancellazione.<\/p>\n<p data-start=\"2265\" data-end=\"2484\">Trattiamo i dati personali secondo il diritto svizzero sulla protezione dei dati. Se applicabile possiamo basarci anche sul Regolamento generale sulla protezione dei dati GDPR in particolare sull\u2019articolo 6 paragrafo 1.<\/p>\n<p data-start=\"2486\" data-end=\"2591\">Trattiamo i dati solo per il tempo necessario agli scopi indicati o per il periodo richiesto dalla legge.<\/p>\n<h2 data-section-id=\"yqneld\" data-start=\"2593\" data-end=\"2602\">Cookie<\/h2>\n<p data-start=\"2603\" data-end=\"2683\">Questo sito utilizza i cookie che sono piccoli file salvati sul tuo dispositivo.<\/p>\n<p data-start=\"2685\" data-end=\"2801\">I cookie servono a migliorare l\u2019esperienza di navigazione, analizzare l\u2019utilizzo del sito e ottimizzare i contenuti.<\/p>\n<p data-start=\"2803\" data-end=\"2925\">I cookie possono rimanere salvati anche dopo la chiusura del browser e possono essere riutilizzati alla visita successiva.<\/p>\n<p data-start=\"2927\" data-end=\"3069\">Puoi disattivare i cookie nelle impostazioni del tuo browser. In questo caso alcune funzioni del sito potrebbero non funzionare correttamente.<\/p>\n<h2 data-section-id=\"fnca1b\" data-start=\"3071\" data-end=\"3092\">Sicurezza dei dati<\/h2>\n<p data-start=\"3093\" data-end=\"3180\">Questo sito utilizza la crittografia SSL o TLS per proteggere la trasmissione dei dati.<\/p>\n<p data-start=\"3182\" data-end=\"3295\">Una connessione sicura \u00e8 riconoscibile dal simbolo del lucchetto e dal prefisso https nell\u2019indirizzo del browser.<\/p>\n<h2 data-section-id=\"1f185z6\" data-start=\"3297\" data-end=\"3322\">File di log del server<\/h2>\n<p data-start=\"3323\" data-end=\"3548\">Il provider del sito raccoglie automaticamente informazioni tecniche nei file di log del server tra cui tipo e versione del browser sistema operativo URL di provenienza nome host del dispositivo ora della richiesta al server.<\/p>\n<p data-start=\"3550\" data-end=\"3645\">Questi dati non vengono assegnati a persone specifiche e non vengono combinati con altre fonti.<\/p>\n<h2 data-section-id=\"1nnrhgi\" data-start=\"3647\" data-end=\"3672\">Servizi di terze parti<\/h2>\n<p data-start=\"3673\" data-end=\"3752\">Questo sito pu\u00f2 utilizzare servizi come Google Maps Google reCAPTCHA e YouTube.<\/p>\n<p data-start=\"3754\" data-end=\"3964\">Questi servizi possono utilizzare cookie e in alcuni casi trasmettere dati a Google negli Stati Uniti. Per quanto ci risulta non avviene alcun tracciamento personale diretto tramite la semplice visita del sito.<\/p>\n<h2 data-section-id=\"1gxdni8\" data-start=\"3966\" data-end=\"3987\">Modulo di contatto<\/h2>\n<p data-start=\"3988\" data-end=\"4177\">Se ci contatti tramite modulo i dati inseriti vengono salvati per gestire la tua richiesta e per eventuali comunicazioni successive. Questi dati non vengono condivisi senza il tuo consenso.<\/p>\n<h2 data-section-id=\"1d89wt5\" data-start=\"4179\" data-end=\"4201\">Diritti dell\u2019utente<\/h2>\n<p data-start=\"4202\" data-end=\"4273\">Hai il diritto di sapere se trattiamo dati personali che ti riguardano.<\/p>\n<p data-start=\"4275\" data-end=\"4324\">Hai il diritto di accesso ai tuoi dati personali.<\/p>\n<p data-start=\"4326\" data-end=\"4367\">Hai il diritto di correggere dati errati.<\/p>\n<p data-start=\"4369\" data-end=\"4478\">Hai il diritto di richiedere la cancellazione dei tuoi dati se sussistono le condizioni previste dalla legge.<\/p>\n<p data-start=\"4480\" data-end=\"4531\">Hai il diritto di limitare il trattamento dei dati.<\/p>\n<p data-start=\"4533\" data-end=\"4574\">Hai il diritto alla portabilit\u00e0 dei dati.<\/p>\n<p data-start=\"4576\" data-end=\"4652\">Hai il diritto di opporti al trattamento dei dati in determinate situazioni.<\/p>\n<p data-start=\"4654\" data-end=\"4714\">Hai il diritto di revocare il consenso in qualsiasi momento.<\/p>\n<h2 data-section-id=\"80hpkb\" data-start=\"4716\" data-end=\"4728\">Modifiche<\/h2>\n<p data-start=\"4729\" data-end=\"4803\">Possiamo aggiornare questa informativa sulla privacy in qualsiasi momento.<\/p>\n<p data-start=\"4805\" data-end=\"4822\" data-is-last-node=\"\" data-is-only-node=\"\">Zurigo 28.08.2023<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sulla privacy La presente informativa sulla privacy ti spiega in modo chiaro come raccogliamo, utilizziamo e trattiamo i dati personali sul nostro sito https:\/\/teasense.ch (di seguito \u201csito\u201d) da parte di Reale Selection (di seguito \u201cnoi\u201d). Ti informa inoltre sui tuoi diritti in materia di protezione dei dati secondo le leggi applicabili. Nome dell\u2019azienda: Reale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":51389,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-51394","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informativa sulla privacy - TeaSense.ch<\/title>\n<meta name=\"description\" content=\"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla privacy - TeaSense.ch\" \/>\n<meta property=\"og:description\" content=\"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"TeaSense.ch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/teasense.ch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/\",\"url\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/\",\"name\":\"Informativa sulla privacy - TeaSense.ch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fna5pazqhmm.jpg\",\"datePublished\":\"2023-05-10T20:07:11+00:00\",\"description\":\"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fna5pazqhmm.jpg\",\"contentUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fna5pazqhmm.jpg\",\"width\":1600,\"height\":1068,\"caption\":\"a golden padlock sitting on top of a keyboard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/teasense.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativa sulla privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/teasense.ch\\\/it\\\/\",\"name\":\"TeaSense.ch\",\"description\":\"Nat\u00fcrliche Teemischungen und klassischer Tee\",\"publisher\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#organization\"},\"alternateName\":\"TeaSense\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teasense.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#organization\",\"name\":\"Reale Selection\",\"alternateName\":\"TeaSense.ch\",\"url\":\"https:\\\/\\\/teasense.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg\",\"contentUrl\":\"https:\\\/\\\/teasense.ch\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg\",\"width\":512,\"height\":512,\"caption\":\"Reale Selection\"},\"image\":{\"@id\":\"https:\\\/\\\/teasense.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teasense.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - TeaSense.ch","description":"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla privacy - TeaSense.ch","og_description":"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.","og_url":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/","og_site_name":"TeaSense.ch","article_publisher":"https:\/\/www.facebook.com\/teasense.ch","og_image":[{"width":1600,"height":1068,"url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/","url":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/","name":"Informativa sulla privacy - TeaSense.ch","isPartOf":{"@id":"https:\/\/teasense.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/#primaryimage"},"image":{"@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/#primaryimage"},"thumbnailUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg","datePublished":"2023-05-10T20:07:11+00:00","description":"Informativa sulla privacy: Attribuiamo grande importanza alla trasparenza e alla protezione dei vostri dati. Pertanto, potete trovare maggiori informazioni sulla nostra raccolta dati qui.","breadcrumb":{"@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/#breadcrumb"},"inLanguage":"it-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/"]}]},{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/#primaryimage","url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg","contentUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg","width":1600,"height":1068,"caption":"a golden padlock sitting on top of a keyboard"},{"@type":"BreadcrumbList","@id":"https:\/\/teasense.ch\/it\/informativa-sulla-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/teasense.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Informativa sulla privacy"}]},{"@type":"WebSite","@id":"https:\/\/teasense.ch\/it\/#website","url":"https:\/\/teasense.ch\/it\/","name":"TeaSense.ch","description":"Nat\u00fcrliche Teemischungen und klassischer Tee","publisher":{"@id":"https:\/\/teasense.ch\/it\/#organization"},"alternateName":"TeaSense","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teasense.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/teasense.ch\/it\/#organization","name":"Reale Selection","alternateName":"TeaSense.ch","url":"https:\/\/teasense.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/teasense.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/07\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg","contentUrl":"https:\/\/teasense.ch\/wp-content\/uploads\/2023\/07\/cropped-logo-teasense-kategorie-onlineshop-alle-produkte.jpg","width":512,"height":512,"caption":"Reale Selection"},"image":{"@id":"https:\/\/teasense.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teasense.ch"]}]}},"jetpack-related-posts":[{"id":51358,"url":"https:\/\/teasense.ch\/it\/cgv\/","url_meta":{"origin":51394,"position":0},"title":"CONDIZIONI GENERALI DI VENDITA (CGV)","author":"Reale Selection","date":"16 February 2017","format":false,"excerpt":"CONDIZIONI GENERALI DI VENDITA (CGV) Reale Selection | teasense.ch Questo sito \u00e8 gestito da Reale Selection. In tutto il sito, i termini \"noi\", \"ci\" e \"nostro\/a\" si riferiscono a Reale Selection. Reale Selection mette a tua disposizione questo sito, comprese tutte le informazioni, gli strumenti e i servizi disponibili, a\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":51234,"url":"https:\/\/teasense.ch\/it\/regali-aziendali-te\/","url_meta":{"origin":51394,"position":1},"title":"Regali aziendali t\u00e8","author":"Reale Selection","date":"18 February 2026","format":false,"excerpt":"Regalare con\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":51383,"url":"https:\/\/teasense.ch\/en\/privacy-policy\/","url_meta":{"origin":51394,"position":2},"title":"Privacy Policy","author":"Reale Selection","date":"10 May 2023","format":false,"excerpt":"Privacy Policy This privacy policy informs you about the nature, scope, and purpose of the collection and use of personal data on our website https:\/\/teasense.ch (hereinafter \u201cwebsite\u201d) by Reale Selection (hereinafter \u201cwe\u201d or \u201cus\u201d) and provides information about your rights. These rights are based on applicable data protection laws. Company\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"a golden padlock sitting on top of a keyboard","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":50525,"url":"https:\/\/teasense.ch\/en\/corporate-tea-gifts\/","url_meta":{"origin":51394,"position":3},"title":"Corporate Tea Gifts","author":"Reale Selection","date":"18 February 2026","format":false,"excerpt":"","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29912,"url":"https:\/\/teasense.ch\/datenschutzerklaerung\/","url_meta":{"origin":51394,"position":4},"title":"Datenschutzerkl\u00e4rung","author":"Reale Selection","date":"10 May 2023","format":false,"excerpt":"Datenschutzerkl\u00e4rung Die vorliegende Datenschutzerkl\u00e4rung kl\u00e4rt Sie \u00fcber die Art, den Umfang und den Zweck der Erhebung und Verwendung personenbezogener Daten auf unserer Website https:\/\/teasense.ch (im Folgenden \u201eWebsite\u201c) durch die Reale Selection (im Folgenden \u201ewir\u201c oder \u201euns\u201c) auf und gibt \u00fcber die Ihnen zustehenden Rechte Auskunft. Diese Rechte richten sich nach\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"a golden padlock sitting on top of a keyboard","src":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/teasense.ch\/wp-content\/uploads\/2023\/08\/fna5pazqhmm.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":51353,"url":"https:\/\/teasense.ch\/en\/gtc\/","url_meta":{"origin":51394,"position":5},"title":"GENERAL TERMS AND CONDITIONS (GTC)","author":"Reale Selection","date":"16 February 2017","format":false,"excerpt":"This website is operated by Reale Selection. Throughout the website, the terms \"we\", \"us\" and \"our\" refer to Reale Selection. Reale Selection offers this website, including all information, tools and services available on it, to you, the user, on the condition that you accept all terms, conditions, policies and notices\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/pages\/51394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/comments?post=51394"}],"version-history":[{"count":0,"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/pages\/51394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/media\/51389"}],"wp:attachment":[{"href":"https:\/\/teasense.ch\/it\/wp-json\/wp\/v2\/media?parent=51394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}